{"id":1611,"date":"2026-02-03T15:40:03","date_gmt":"2026-02-03T07:40:03","guid":{"rendered":"https:\/\/www.yasenn.com\/?post_type=product&#038;p=1611"},"modified":"2026-02-03T19:43:25","modified_gmt":"2026-02-03T11:43:25","slug":"delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051","status":"publish","type":"product","link":"https:\/\/www.yasenn.com\/fr\/produit\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/","title":{"rendered":"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051"},"content":{"rendered":"<p data-start=\"129\" data-end=\"333\"><strong data-start=\"129\" data-end=\"333\">A charming artificial pea blossom stem featuring 5 delicate 3.5 cm flowers and 15 lifelike leaves, designed to bring a fresh, natural beauty to your floral arrangements, home d\u00e9cor, and event styling.<\/strong><\/p>\n<hr data-start=\"335\" data-end=\"338\" \/>\n<h3 data-start=\"340\" data-end=\"362\">Product Highlights<\/h3>\n<ul data-start=\"363\" data-end=\"652\">\n<li data-start=\"363\" data-end=\"440\">\n<p data-start=\"365\" data-end=\"440\">5 flowers (3.5 cm each) on a single stem for a delicate, cascading effect<\/p>\n<\/li>\n<li data-start=\"441\" data-end=\"520\">\n<p data-start=\"443\" data-end=\"520\">15 realistic leaves to complement the flowers and complete the natural look<\/p>\n<\/li>\n<li data-start=\"521\" data-end=\"600\">\n<p data-start=\"523\" data-end=\"600\">65 cm height, perfect for vases, centerpieces, or mixed floral arrangements<\/p>\n<\/li>\n<li data-start=\"601\" data-end=\"652\">\n<p data-start=\"603\" data-end=\"652\">Pongee material for a soft and lifelike texture<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"654\" data-end=\"657\" \/>\n<h3 data-start=\"659\" data-end=\"687\">Material &amp; Craftsmanship<\/h3>\n<ul data-start=\"688\" data-end=\"990\">\n<li data-start=\"688\" data-end=\"773\">\n<p data-start=\"690\" data-end=\"773\">High-quality Pongee fabric provides a lifelike feel with excellent color fidelity<\/p>\n<\/li>\n<li data-start=\"774\" data-end=\"852\">\n<p data-start=\"776\" data-end=\"852\">Each flower and leaf is meticulously crafted to resemble real pea blossoms<\/p>\n<\/li>\n<li data-start=\"853\" data-end=\"917\">\n<p data-start=\"855\" data-end=\"917\">Flexible yet sturdy stem allows for easy shaping and styling<\/p>\n<\/li>\n<li data-start=\"918\" data-end=\"990\">\n<p data-start=\"920\" data-end=\"990\">Fade-resistant and durable, designed for long-lasting decorative use<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"992\" data-end=\"995\" \/>\n<h3 data-start=\"997\" data-end=\"1022\">Application Scenarios<\/h3>\n<ul data-start=\"1023\" data-end=\"1220\">\n<li data-start=\"1023\" data-end=\"1074\">\n<p data-start=\"1025\" data-end=\"1074\">Floral arrangements, bouquets, and centerpieces<\/p>\n<\/li>\n<li data-start=\"1075\" data-end=\"1111\">\n<p data-start=\"1077\" data-end=\"1111\">Wedding and event floral styling<\/p>\n<\/li>\n<li data-start=\"1112\" data-end=\"1157\">\n<p data-start=\"1114\" data-end=\"1157\">Home d\u00e9cor, table centerpieces, and vases<\/p>\n<\/li>\n<li data-start=\"1158\" data-end=\"1220\">\n<p data-start=\"1160\" data-end=\"1220\">Commercial displays and long-term decorative installations<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1222\" data-end=\"1225\" \/>\n<h3 data-start=\"1227\" data-end=\"1245\">Specifications<\/h3>\n<ul data-start=\"1246\" data-end=\"1383\">\n<li data-start=\"1246\" data-end=\"1268\">\n<p data-start=\"1248\" data-end=\"1268\">Item No.: YSF20051<\/p>\n<\/li>\n<li data-start=\"1269\" data-end=\"1297\">\n<p data-start=\"1271\" data-end=\"1297\">Flower Name: Pea Blossom<\/p>\n<\/li>\n<li data-start=\"1298\" data-end=\"1315\">\n<p data-start=\"1300\" data-end=\"1315\">Height: 65 cm<\/p>\n<\/li>\n<li data-start=\"1316\" data-end=\"1343\">\n<p data-start=\"1318\" data-end=\"1343\">Flower Diameter: 3.5 cm<\/p>\n<\/li>\n<li data-start=\"1344\" data-end=\"1364\">\n<p data-start=\"1346\" data-end=\"1364\">Material: Pongee<\/p>\n<\/li>\n<li data-start=\"1365\" data-end=\"1383\">\n<p data-start=\"1367\" data-end=\"1383\">Leaves: 15 pcs<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1385\" data-end=\"1388\" \/>\n<h3 data-start=\"1390\" data-end=\"1413\">Packing Information<\/h3>\n<ul data-start=\"1414\" data-end=\"1482\">\n<li data-start=\"1414\" data-end=\"1448\">\n<p data-start=\"1416\" data-end=\"1448\">Packing Qty: 60\/360<\/p>\n<\/li>\n<li data-start=\"1449\" data-end=\"1482\">\n<p data-start=\"1451\" data-end=\"1482\">Carton Size: 112 \u00d7 37 \u00d7 64 cm<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1484\" data-end=\"1487\" \/>\n<h3 data-start=\"1489\" data-end=\"1506\">Why Choose Us<\/h3>\n<ul data-start=\"1507\" data-end=\"1785\">\n<li data-start=\"1507\" data-end=\"1572\">\n<p data-start=\"1509\" data-end=\"1572\">Over 20 years of expertise in artificial floral manufacturing<\/p>\n<\/li>\n<li data-start=\"1573\" data-end=\"1635\">\n<p data-start=\"1575\" data-end=\"1635\">Specialized in realistic and decorative artificial flowers<\/p>\n<\/li>\n<li data-start=\"1636\" data-end=\"1688\">\n<p data-start=\"1638\" data-end=\"1688\">Stable quality for bulk and project-based orders<\/p>\n<\/li>\n<li data-start=\"1689\" data-end=\"1734\">\n<p data-start=\"1691\" data-end=\"1734\">Custom color and design options available<\/p>\n<\/li>\n<li data-start=\"1735\" data-end=\"1785\">\n<p data-start=\"1737\" data-end=\"1785\">Reliable packaging and global shipping support<\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Item No.\uff1aYSF20051<br \/>\nHeight\uff1a65CM<br \/>\nFlower Name\uff1apea blossom<br \/>\nMaterial\uff1aPONGEE<br \/>\nDia of Flower\uff1a3.5CM<br \/>\nLeaves\uff1a15PCS LEAVES<br \/>\nPacking Inf.\uff1a60\/360 112*37*64<br \/>\nDescription\uff1aHEIGHT 65CM\/5PCS FLOWERS\/PONGEE\/DIA 3.5CM\/15PCS LEAVES<\/p>","protected":false},"featured_media":1612,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[50,24,69],"product_tag":[],"class_list":{"0":"post-1611","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-artificial-flowers","7":"product_cat-single","8":"product_cat-spring-flowers","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051 - artificial flower<\/title>\n<meta name=\"description\" content=\"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yasenn.com\/fr\/produit\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051\" \/>\n<meta property=\"og:description\" content=\"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yasenn.com\/fr\/produit\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/\" \/>\n<meta property=\"og:site_name\" content=\"artificial flower\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573710847136\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T11:43:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/\",\"url\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/\",\"name\":\"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051 - artificial flower\",\"isPartOf\":{\"@id\":\"https:\/\/www.yasenn.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg\",\"datePublished\":\"2026-02-03T07:40:03+00:00\",\"dateModified\":\"2026-02-03T11:43:25+00:00\",\"description\":\"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage\",\"url\":\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg\",\"contentUrl\":\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.yasenn.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.yasenn.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.yasenn.com\/#website\",\"url\":\"https:\/\/www.yasenn.com\/\",\"name\":\"YASHEN artificial flower\",\"description\":\"artificial flower Manufacturer from China.YASHEN ARTS\",\"publisher\":{\"@id\":\"https:\/\/www.yasenn.com\/#organization\"},\"alternateName\":\"YASENN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.yasenn.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\",\"Manufacturer\"],\"@id\":\"https:\/\/www.yasenn.com\/#organization\",\"name\":\"YASHEN ARTS AND CRAFT CO.LTD\",\"alternateName\":\"YASENN\",\"url\":\"https:\/\/www.yasenn.com\/\",\"logo\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61573710847136\"],\"description\":\"Premier Silk & Artificial Flowers Manufacturer: Offering Competitive Pricing, Exquisite Realism, and Fully Customizable Designs Direct from China.\",\"legalName\":\"YASHEN ARTS AND CRAFT CO.LTD\",\"foundingDate\":\"2005-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"address\":{\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-place-address\"},\"telephone\":[\"+8657985371215\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"yasenn@yasenn.com\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-place-address\",\"streetAddress\":\"206 Yongjun Road\",\"addressLocality\":\"Yiwu City\",\"postalCode\":\"322000\",\"addressRegion\":\"Zhejiang\",\"addressCountry\":\"CN\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo\",\"url\":\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/01\/YASENN-logo-1.gif\",\"contentUrl\":\"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/01\/YASENN-logo-1.gif\",\"width\":762,\"height\":204,\"caption\":\"YASHEN ARTS AND CRAFT CO.LTD\"}]}<\/script>\n<meta property=\"product:price:currency\" content=\"CNY\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Yiwu City\" \/>\n<meta name=\"geo.region\" content=\"Chine\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051 - artificial flower","description":"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yasenn.com\/fr\/produit\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/","og_locale":"fr_FR","og_type":"article","og_title":"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051","og_description":"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.","og_url":"https:\/\/www.yasenn.com\/fr\/produit\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/","og_site_name":"artificial flower","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573710847136","article_modified_time":"2026-02-03T11:43:25+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/","url":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/","name":"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051 - artificial flower","isPartOf":{"@id":"https:\/\/www.yasenn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage"},"image":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg","datePublished":"2026-02-03T07:40:03+00:00","dateModified":"2026-02-03T11:43:25+00:00","description":"Elegant 65 cm artificial pea blossom stem with 5 flowers (3.5 cm) and 15 leaves, perfect for floral arrangements, home d\u00e9cor, and event styling.","breadcrumb":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#primaryimage","url":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg","contentUrl":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/02\/YSF20051.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.yasenn.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.yasenn.com\/products\/"},{"@type":"ListItem","position":3,"name":"Delicate Pea Blossom Stem \u2013 Lifelike Floral Accent YSF20051"}]},{"@type":"WebSite","@id":"https:\/\/www.yasenn.com\/#website","url":"https:\/\/www.yasenn.com\/","name":"YASHEN artificial flower","description":"artificial flower Manufacturer from China.YASHEN ARTS","publisher":{"@id":"https:\/\/www.yasenn.com\/#organization"},"alternateName":"YASENN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yasenn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place","Manufacturer"],"@id":"https:\/\/www.yasenn.com\/#organization","name":"YASHEN ARTS AND CRAFT CO.LTD","alternateName":"YASENN","url":"https:\/\/www.yasenn.com\/","logo":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573710847136"],"description":"Premier Silk & Artificial Flowers Manufacturer: Offering Competitive Pricing, Exquisite Realism, and Fully Customizable Designs Direct from China.","legalName":"YASHEN ARTS AND CRAFT CO.LTD","foundingDate":"2005-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"address":{"@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-place-address"},"telephone":["+8657985371215"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"yasenn@yasenn.com"},{"@type":"PostalAddress","@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-place-address","streetAddress":"206 Yongjun Road","addressLocality":"Yiwu City","postalCode":"322000","addressRegion":"Zhejiang","addressCountry":"CN"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yasenn.com\/product\/delicate-pea-blossom-stem-lifelike-floral-accent-ysf20051\/#local-main-organization-logo","url":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/01\/YASENN-logo-1.gif","contentUrl":"https:\/\/www.yasenn.com\/wp-content\/uploads\/2026\/01\/YASENN-logo-1.gif","width":762,"height":204,"caption":"YASHEN ARTS AND CRAFT CO.LTD"}]},"product_price_currency":"CNY","og_availability":"instock","product_availability":"instock","product_condition":"new","geo.placename":"Yiwu City","geo.region":"Chine"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/product\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/comments?post=1611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/media\/1612"}],"wp:attachment":[{"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1611"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.yasenn.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}